{"id":4223,"date":"2025-12-27T15:56:21","date_gmt":"2025-12-27T07:56:21","guid":{"rendered":"https:\/\/www.bali-island.com\/?p=4223"},"modified":"2025-12-27T15:56:21","modified_gmt":"2025-12-27T07:56:21","slug":"daftar-lengkap-menu-subway","status":"publish","type":"post","link":"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/","title":{"rendered":"Vollst\u00e4ndige Subway Men\u00fcliste 2026"},"content":{"rendered":"<p>Subway ist eine amerikanische Fast-Food-Kette, die f\u00fcr ihr Hauptmen\u00fc aus <b>langen Sandwiches (U-Boot-Sandwiches)<\/b>\u00a0und auch Salaten bekannt ist. Im Gegensatz zu den meisten Fast-Food-Lokalen, die mit Burgern oder frittiertem H\u00e4hnchen identifiziert werden, konzentriert sich Subway auf belegte Brote, die an den jeweiligen Geschmack angepasst werden k\u00f6nnen.<\/p>\n<p>Eines der Dinge, die Subway interessant machen, ist die interaktive Art der Zubereitung. Zuerst w\u00e4hlen wir das gew\u00fcnschte Sandwich- oder Salat-Men\u00fc. Wenn wir ein Sandwich w\u00e4hlen, besteht der n\u00e4chste Schritt darin, die Brotsorte zu bestimmen. Danach k\u00f6nnen wir frei verschiedene F\u00fcllungen w\u00e4hlen, von Fleisch bis hin zu zus\u00e4tzlichen Toppings. Darauf folgt eine Auswahl an frischem Gem\u00fcse, und zum Schluss muss nur noch die Lieblingsso\u00dfe nach Geschmack bestimmt werden.<\/p>\n<p>Kurz gesagt, jedes Subway-Men\u00fc kann an unsere eigenen W\u00fcnsche angepasst werden, es ist praktisch, flexibel und geeignet f\u00fcr diejenigen, die eine schnelle Mahlzeit w\u00fcnschen, die sich aber dennoch pers\u00f6nlich anf\u00fchlt. Das Folgende ist eine vollst\u00e4ndige Liste des Subway Indonesien-Men\u00fcs:<\/p>\n<h2><b>Sandwiches<\/b><\/h2>\n<p>Sandwiches sind das belegte Brot, das das Markenzeichen von Subway ist. Hier ist die vollst\u00e4ndige Liste:<\/p>\n<ul>\n<li>Captain Fish (Kapit\u00e4n Fisch)<\/li>\n<li>Beef Pastrami (Rindfleisch Pastrami)<\/li>\n<li>Ultimate Cheese Steak (Ultimatives K\u00e4se-Steak)<\/li>\n<li>Ultimate Spicy Supreme (Ultimatives Scharfes Supreme)<\/li>\n<li>Subway Double BLT (Subway Doppel BLT)<\/li>\n<li>Roast Beef (Roastbeef)<\/li>\n<li>Chicken Teriyaki (H\u00e4hnchen Teriyaki)<\/li>\n<li>BBQ Chicken (BBQ H\u00e4hnchen)<\/li>\n<li>Chicken Slice (H\u00e4hnchenscheiben)<\/li>\n<li>Tuna Mayo (Thunfisch Mayonnaise)<\/li>\n<li>Steak &amp; Cheese (Steak &amp; K\u00e4se)<\/li>\n<li>Italian B.M.T (Italienisch B.M.T)<\/li>\n<li>Roast Chicken (Gebratenes H\u00e4hnchen)<\/li>\n<li>Veggie Delite (Gem\u00fcse Genuss)<\/li>\n<li>Spicy Italian (Scharfer Italiener)<\/li>\n<li>Egg Mayo (Ei Mayonnaise)<\/li>\n<\/ul>\n<h2><\/h2>\n<h2><b>Brotsorten<\/b><\/h2>\n<p>Hier sind die Brotsorten, die f\u00fcr die Sandwiches verwendet werden:<\/p>\n<ul>\n<li>White Bread (Wei\u00dfbrot)<\/li>\n<li>Wheat Bread (Weizenbrot)<\/li>\n<li>White Honey Oat (Wei\u00df Honig Hafer)<\/li>\n<li>White Parmesan Oregano Bread (Wei\u00df Parmesan Oregano Brot)<\/li>\n<li>White Garlic Bread (Wei\u00df Knoblauch Brot)<\/li>\n<\/ul>\n<h2><\/h2>\n<h2><b>Wraps<\/b><\/h2>\n<p>Wraps sind Sandwich-F\u00fcllungen, die in einer weichen Tortilla eingewickelt sind. Hier ist die vollst\u00e4ndige Liste des Wrap-Men\u00fcs:<\/p>\n<ul>\n<li>BBQ Chicken (BBQ H\u00e4hnchen)<\/li>\n<li>Chicken Slice (H\u00e4hnchenscheiben)<\/li>\n<li>Chicken Teriyaki (H\u00e4hnchen Teriyaki)<\/li>\n<li>Egg Mayo (Ei Mayonnaise)<\/li>\n<li>Italian B.M.T (Italienisch B.M.T)<\/li>\n<li>Roast Chicken (Gebratenes H\u00e4hnchen)<\/li>\n<li>Spicy Italian (Scharfer Italiener)<\/li>\n<li>Steak &amp; Cheese (Steak &amp; K\u00e4se)<\/li>\n<li>Tuna Mayo (Thunfisch Mayonnaise)<\/li>\n<li>Veggie Delite (Gem\u00fcse Genuss)<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2><b>Beilagen (Sides)<\/b><\/h2>\n<p>Hier ist die vollst\u00e4ndige Liste der w\u00e4hlbaren Beilagen:<\/p>\n<ul>\n<li>Cookie Chocolate Chip (Keks Schokoladenst\u00fcckchen)<\/li>\n<li>Cookie Double Chocolate Chip (Keks Doppel Schokoladenst\u00fcckchen)<\/li>\n<li>Cookie Oatmeal Raisin (Keks Haferflocken Rosine)<\/li>\n<li>Cookie White Chip Macadamia Nut (Keks Wei\u00dfe St\u00fcckchen Macadamia-Nuss)<\/li>\n<li>Doritos Jagung Bakar (Doritos Ger\u00f6steter Mais)<\/li>\n<li>Doritos Sambal Salsa (Doritos Chili Salsa)<\/li>\n<li>Soup Chicken Cream (Suppe H\u00e4hnchen-Creme)<\/li>\n<li>Soup Mushroom (Suppe Pilz)<\/li>\n<li>Subway Fries Waffle (Subway Waffel-Pommes)<\/li>\n<li>Subway Hashbrown<\/li>\n<li>Subway Mac &amp; Cheese<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2><b>Getr\u00e4nke<\/b><\/h2>\n<p>Hier ist die vollst\u00e4ndige Liste der Getr\u00e4nke:<\/p>\n<ul>\n<li>Aqua 300ml<\/li>\n<li>Carbonated Drinks (Cola Cola\/Fanta\/Sprite) (Kohlens\u00e4urehaltige Getr\u00e4nke)<\/li>\n<li>Iced Green Tea (Eis-Gr\u00fcntee)<\/li>\n<li>Iced Lemon Tea (Eis-Zitronentee)<\/li>\n<li>Iced Lemonade (Eis-Limonade)<\/li>\n<li>MILO<\/li>\n<li>Minute maid Pulpy orange (Minute Maid Fruchtfleisch Orange)<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2><b>Promo-Men\u00fc<\/b><\/h2>\n<p>Zum Zeitpunkt des Besuchs gab es bei Subway ein Promo-Men\u00fc, n\u00e4mlich Sub Delas 50K, bei dem dieses Men\u00fc ein B\u00fcndelkauf f\u00fcr 1 Sandwich + 1 Getr\u00e4nk f\u00fcr etwa f\u00fcnfzigtausend Rupiah ist. Die Getr\u00e4nkeauswahl gilt f\u00fcr alle Tee- und Softdrink-Sorten. Die Sandwiches, die an dieser Aktion teilnehmen, sind:<\/p>\n<ul>\n<li>Chick N Tuna (H\u00e4hnchen und Thunfisch)<\/li>\n<li>Tuna N Egg (Thunfisch und Ei)<\/li>\n<li>Chick N Chick (H\u00e4hnchen und H\u00e4hnchen)<\/li>\n<li>Chicken N Egg (H\u00e4hnchen und Ei)<\/li>\n<li>Beef N egg (Rindfleisch und Ei)<\/li>\n<li>Cheese N Egg (K\u00e4se und Ei)<\/li>\n<\/ul>\n<figure id=\"attachment_4201\" aria-describedby=\"caption-attachment-4201\" style=\"width: 680px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.bali-island.com\/wp-content\/uploads\/2025\/12\/Sandwich-Subway.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-4201\" src=\"https:\/\/www.bali-island.com\/wp-content\/uploads\/2025\/12\/Sandwich-Subway-700x400.jpeg\" alt=\"Sandwich Subway\" width=\"680\" height=\"389\" \/><\/a><figcaption id=\"caption-attachment-4201\" class=\"wp-caption-text\">Sandwich Subway<\/figcaption><\/figure>\n<figure id=\"attachment_4192\" aria-describedby=\"caption-attachment-4192\" style=\"width: 680px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.bali-island.com\/wp-content\/uploads\/2025\/12\/Menu-Subway.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-4192\" src=\"https:\/\/www.bali-island.com\/wp-content\/uploads\/2025\/12\/Menu-Subway-700x400.jpeg\" alt=\"Menu Subway\" width=\"680\" height=\"389\" \/><\/a><figcaption id=\"caption-attachment-4192\" class=\"wp-caption-text\">Menu Subway<\/figcaption><\/figure>\n<figure id=\"attachment_4183\" aria-describedby=\"caption-attachment-4183\" style=\"width: 680px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.bali-island.com\/wp-content\/uploads\/2025\/12\/Add-On-Subway.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-4183\" src=\"https:\/\/www.bali-island.com\/wp-content\/uploads\/2025\/12\/Add-On-Subway-700x400.jpeg\" alt=\"Add On Subway\" width=\"680\" height=\"389\" \/><\/a><figcaption id=\"caption-attachment-4183\" class=\"wp-caption-text\">Add On Subway<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Subway ist eine amerikanische Fast-Food-Kette, die f\u00fcr ihr&#8230;<\/p>\n","protected":false},"author":1,"featured_media":4210,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[91],"tags":[],"newstopic":[],"class_list":["post-4223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kulinarik"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vollst\u00e4ndige Subway Men\u00fcliste 2026<\/title>\n<meta name=\"description\" content=\"Sehen Sie sich die vollst\u00e4ndigen Subway-Men\u00fcoptionen an, von Sandwiches, Wraps, Salaten bis hin zu Beilagen, komplett mit attraktiven Promo-Men\u00fcs.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vollst\u00e4ndige Subway Men\u00fcliste 2026\" \/>\n<meta property=\"og:description\" content=\"Sehen Sie sich die vollst\u00e4ndigen Subway-Men\u00fcoptionen an, von Sandwiches, Wraps, Salaten bis hin zu Beilagen, komplett mit attraktiven Promo-Men\u00fcs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/\" \/>\n<meta property=\"og:site_name\" content=\"Bali Island\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Bali-Island\/61575583076902\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-27T07:56:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bali-island.com\/wp-content\/uploads\/2025\/12\/Subway.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\/\/www.bali-island.com\/de\/#\/schema\/person\/fa4ad517d8835db1504e3c7c3ddd02ab\"},\"headline\":\"Vollst\u00e4ndige Subway Men\u00fcliste 2026\",\"datePublished\":\"2025-12-27T07:56:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/\"},\"wordCount\":634,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.bali-island.com\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bali-island.com\/wp-content\/uploads\/2025\/12\/Subway.jpeg\",\"articleSection\":[\"Kulinarik\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/\",\"url\":\"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/\",\"name\":\"Vollst\u00e4ndige Subway Men\u00fcliste 2026\",\"isPartOf\":{\"@id\":\"https:\/\/www.bali-island.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.bali-island.com\/wp-content\/uploads\/2025\/12\/Subway.jpeg\",\"datePublished\":\"2025-12-27T07:56:21+00:00\",\"description\":\"Sehen Sie sich die vollst\u00e4ndigen Subway-Men\u00fcoptionen an, von Sandwiches, Wraps, Salaten bis hin zu Beilagen, komplett mit attraktiven Promo-Men\u00fcs.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/#primaryimage\",\"url\":\"https:\/\/www.bali-island.com\/wp-content\/uploads\/2025\/12\/Subway.jpeg\",\"contentUrl\":\"https:\/\/www.bali-island.com\/wp-content\/uploads\/2025\/12\/Subway.jpeg\",\"width\":1280,\"height\":720,\"caption\":\"Subway\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.bali-island.com\/de\/bali-insel-ihr-vollstandiger-reisefuhrer-fur-bali-indonesien\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vollst\u00e4ndige Subway Men\u00fcliste 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bali-island.com\/de\/#website\",\"url\":\"https:\/\/www.bali-island.com\/de\/\",\"name\":\"Bali Island\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.bali-island.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bali-island.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.bali-island.com\/de\/#organization\",\"name\":\"Insel Bali\",\"alternateName\":\"BI\",\"url\":\"https:\/\/www.bali-island.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.bali-island.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.bali-island.com\/wp-content\/uploads\/2025\/04\/cropped-Untitled_design__13_-removebg-preview-1.png\",\"contentUrl\":\"https:\/\/www.bali-island.com\/wp-content\/uploads\/2025\/04\/cropped-Untitled_design__13_-removebg-preview-1.png\",\"width\":512,\"height\":512,\"caption\":\"Insel Bali\"},\"image\":{\"@id\":\"https:\/\/www.bali-island.com\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/people\/Bali-Island\/61575583076902\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bali-island.com\/de\/#\/schema\/person\/fa4ad517d8835db1504e3c7c3ddd02ab\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.bali-island.com\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.bali-island.com\/wp-content\/litespeed\/avatar\/736da4bc12e223a28c23d17b545d8b2e.jpg?ver=1783768134\",\"contentUrl\":\"https:\/\/www.bali-island.com\/wp-content\/litespeed\/avatar\/736da4bc12e223a28c23d17b545d8b2e.jpg?ver=1783768134\",\"caption\":\"Admin\"},\"sameAs\":[\"http:\/\/bali-island.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vollst\u00e4ndige Subway Men\u00fcliste 2026","description":"Sehen Sie sich die vollst\u00e4ndigen Subway-Men\u00fcoptionen an, von Sandwiches, Wraps, Salaten bis hin zu Beilagen, komplett mit attraktiven Promo-Men\u00fcs.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/","og_locale":"de_DE","og_type":"article","og_title":"Vollst\u00e4ndige Subway Men\u00fcliste 2026","og_description":"Sehen Sie sich die vollst\u00e4ndigen Subway-Men\u00fcoptionen an, von Sandwiches, Wraps, Salaten bis hin zu Beilagen, komplett mit attraktiven Promo-Men\u00fcs.","og_url":"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/","og_site_name":"Bali Island","article_publisher":"https:\/\/www.facebook.com\/people\/Bali-Island\/61575583076902\/","article_published_time":"2025-12-27T07:56:21+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.bali-island.com\/wp-content\/uploads\/2025\/12\/Subway.jpeg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Admin","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/#article","isPartOf":{"@id":"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/"},"author":{"name":"Admin","@id":"https:\/\/www.bali-island.com\/de\/#\/schema\/person\/fa4ad517d8835db1504e3c7c3ddd02ab"},"headline":"Vollst\u00e4ndige Subway Men\u00fcliste 2026","datePublished":"2025-12-27T07:56:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/"},"wordCount":634,"commentCount":0,"publisher":{"@id":"https:\/\/www.bali-island.com\/de\/#organization"},"image":{"@id":"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bali-island.com\/wp-content\/uploads\/2025\/12\/Subway.jpeg","articleSection":["Kulinarik"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/","url":"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/","name":"Vollst\u00e4ndige Subway Men\u00fcliste 2026","isPartOf":{"@id":"https:\/\/www.bali-island.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/#primaryimage"},"image":{"@id":"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bali-island.com\/wp-content\/uploads\/2025\/12\/Subway.jpeg","datePublished":"2025-12-27T07:56:21+00:00","description":"Sehen Sie sich die vollst\u00e4ndigen Subway-Men\u00fcoptionen an, von Sandwiches, Wraps, Salaten bis hin zu Beilagen, komplett mit attraktiven Promo-Men\u00fcs.","breadcrumb":{"@id":"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/#primaryimage","url":"https:\/\/www.bali-island.com\/wp-content\/uploads\/2025\/12\/Subway.jpeg","contentUrl":"https:\/\/www.bali-island.com\/wp-content\/uploads\/2025\/12\/Subway.jpeg","width":1280,"height":720,"caption":"Subway"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bali-island.com\/de\/kulinarik\/daftar-lengkap-menu-subway\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bali-island.com\/de\/bali-insel-ihr-vollstandiger-reisefuhrer-fur-bali-indonesien\/"},{"@type":"ListItem","position":2,"name":"Vollst\u00e4ndige Subway Men\u00fcliste 2026"}]},{"@type":"WebSite","@id":"https:\/\/www.bali-island.com\/de\/#website","url":"https:\/\/www.bali-island.com\/de\/","name":"Bali Island","description":"","publisher":{"@id":"https:\/\/www.bali-island.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bali-island.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.bali-island.com\/de\/#organization","name":"Insel Bali","alternateName":"BI","url":"https:\/\/www.bali-island.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.bali-island.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.bali-island.com\/wp-content\/uploads\/2025\/04\/cropped-Untitled_design__13_-removebg-preview-1.png","contentUrl":"https:\/\/www.bali-island.com\/wp-content\/uploads\/2025\/04\/cropped-Untitled_design__13_-removebg-preview-1.png","width":512,"height":512,"caption":"Insel Bali"},"image":{"@id":"https:\/\/www.bali-island.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Bali-Island\/61575583076902\/"]},{"@type":"Person","@id":"https:\/\/www.bali-island.com\/de\/#\/schema\/person\/fa4ad517d8835db1504e3c7c3ddd02ab","name":"Admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.bali-island.com\/de\/#\/schema\/person\/image\/","url":"https:\/\/www.bali-island.com\/wp-content\/litespeed\/avatar\/736da4bc12e223a28c23d17b545d8b2e.jpg?ver=1783768134","contentUrl":"https:\/\/www.bali-island.com\/wp-content\/litespeed\/avatar\/736da4bc12e223a28c23d17b545d8b2e.jpg?ver=1783768134","caption":"Admin"},"sameAs":["http:\/\/bali-island.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.bali-island.com\/de\/wp-json\/wp\/v2\/posts\/4223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bali-island.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bali-island.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bali-island.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bali-island.com\/de\/wp-json\/wp\/v2\/comments?post=4223"}],"version-history":[{"count":1,"href":"https:\/\/www.bali-island.com\/de\/wp-json\/wp\/v2\/posts\/4223\/revisions"}],"predecessor-version":[{"id":4224,"href":"https:\/\/www.bali-island.com\/de\/wp-json\/wp\/v2\/posts\/4223\/revisions\/4224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bali-island.com\/de\/wp-json\/wp\/v2\/media\/4210"}],"wp:attachment":[{"href":"https:\/\/www.bali-island.com\/de\/wp-json\/wp\/v2\/media?parent=4223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bali-island.com\/de\/wp-json\/wp\/v2\/categories?post=4223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bali-island.com\/de\/wp-json\/wp\/v2\/tags?post=4223"},{"taxonomy":"newstopic","embeddable":true,"href":"https:\/\/www.bali-island.com\/de\/wp-json\/wp\/v2\/newstopic?post=4223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}